{"id":3310,"date":"2025-12-19T10:29:38","date_gmt":"2025-12-19T10:29:38","guid":{"rendered":"https:\/\/www.unser-weissensee.de\/?p=3310"},"modified":"2025-12-19T10:30:39","modified_gmt":"2025-12-19T10:30:39","slug":"neujahrsgruss-des-freizeithaus-e-v","status":"publish","type":"post","link":"https:\/\/www.unser-weissensee.de\/index.php\/2025\/12\/19\/neujahrsgruss-des-freizeithaus-e-v\/","title":{"rendered":"Neujahrsgru\u00df des FreiZeitHaus e. V."},"content":{"rendered":"\n<p><strong>Liebe Mitglieder des FreiZeitHaus e.V., liebe ehrenamtlich Engagierte in unseren Einrichtungen,<\/strong><\/p>\n\n\n\n<p>am Jahresende erz\u00e4hlen viele von runden Erfolgen. Von Kurven, die nach oben zeigen, und erfolgreich \u201eeinget\u00fcteten\u201c Projekten. Die Geschichten, die uns in unserer Arbeit begegnen sehen an manchen Stellen anders aus. Wir arbeiten in einem Feld, in dem es um Menschen geht: mit Hoffnungen, Konto\u00adst\u00e4nden, Auseinandersetzungen im Familien- oder Freundeskreis, bewegten Biografien. Zugleich sind wir Teil eines Systems, das um Haushaltsk\u00fcrzungen, Personalf\u00f6rderung und Arbeitsschutz ringt. Unter diesen Bedingungen verl\u00e4uft kaum ein Weg wirklich geradeaus.<\/p>\n\n\n\n<p>Was wir im zur\u00fcckliegenden Jahr zunehmend festgestellt haben: Es f\u00e4llt vielen gerade schwer, gro\u00dfe Schritte zu tun. Viele tr\u00e4umen zwar von einem beziehungsreicheren Leben, aber die Kombination aus wirtschaftlicher und politischer Unsicherheit, famili\u00e4ren Sorgen und \u201ealles zuviel\u201c macht manchmal den Schritt aus dem Haus, den Schritt zu mehr Selbstf\u00fcrsorge und den Schritt in die Gemeinschaft herausfordernd. Der Wunsch nach Zugeh\u00f6rigkeit ringt mit der Angst, sich zu \u00fcberfordern.<\/p>\n\n\n\n<p>Immer wieder sp\u00fcren wir aber auch: Wenn viele H\u00e4nde, kluge K\u00f6pfe und warme Herzen zusammenkommen, entstehen Dinge, die man nicht f\u00fcr m\u00f6glich gehalten h\u00e4tte, so zum Beispiel in dem neuen Format des Fair Caf\u00e9s im Stadtteilzentrum \u2013 hier gibt es immer donnerstags zwischen 14 und 17 Uhr die M\u00f6glichkeit sich mit anderen Menschen zu vernetzen, kostenlos gerettete Lebensmittel zu teilen und in Gemeinschaft Projektideen f\u00fcr die Nachbarschaft zu entwickeln.<\/p>\n\n\n\n<p>Es lohnt sich, an Orten zu wirken, an denen Bindung und Beziehung ge\u00fcbt werden k\u00f6nnen.<\/p>\n\n\n\n<p>Es lohnt sich, R\u00e4ume zu halten, in denen auch Reibung ihren Platz findet.<\/p>\n\n\n\n<p>Es lohnt sich, auch dann weiterzumachen, wenn die Energie mal nachl\u00e4sst und Kraft dort zu sch\u00f6pfen, wo Neues entsteht und sich Beziehungen verdichten.<\/p>\n\n\n\n<p>Wir m\u00f6chten uns bei alle denjenigen bedanken, die das Jahr 2025 im FreiZeitHaus e.V. bereichert und unterst\u00fctzt haben. Die gelebte Vielfalt in unserem Verein wurde gepr\u00e4gt durch diejenigen, die uns t\u00e4glich aufsuchen, sich ehrenamtlich einbringen und gemeinsam mit uns die Nachbarschaft aktiv gestalten.<\/p>\n\n\n\n<p><strong>Vielen Dank f\u00fcr Ihr Zutun!<\/strong><\/p>\n\n\n\n<p>Im Jahr 2025 hat der FreiZeitHaus e.V. sein 35. j\u00e4hriges Bestehen gefeiert. Eher still und leise, dabei haben uns ganz gro\u00dfartige Gru\u00dfworte aus Politik, Verwaltung und von engen Wegbegleiter*innen erreicht. Schauen Sie mal online vorbei und lassen Sie sich etwas zu der Geschichte des Vereins <a href=\"https:\/\/www.frei-zeit-haus.de\/aktuelles\/jubil%C3%A4um.html\">erz\u00e4hlen<\/a>!<\/p>\n\n\n\n<p>Dass diese Arbeit und unser gemeinsames Wirken f\u00fcr die Berliner Stadtgesellschaft erneut und weiterhin durch K\u00fcrzungen bedroht ist, frustriert. Und die Mitarbeitenden sind aufgrund der stetigen Unsicherheit\/en ersch\u00f6pft. M\u00f6ge das neue Jahr und die anstehende Wahl in Berlin 2026 dazu f\u00fchren, dass die soziale Arbeit R\u00fcckenwind erh\u00e4lt und das stetige Bangen, wie und ob es weitergeht, ein Ende hat. Ohne eine solche Unterst\u00fctzung zum Erhalt der sozialen Infrastruktur in Pankow und dieser Stadt, ger\u00e4t auch die Zukunft von Demokratief\u00f6rderung, Familienbildung, Partizipation, Inklusion und Gemeinschaft in unserer Nachbarschaft in Gefahr!<\/p>\n\n\n\n<p><em>Wenn Sie uns in diesen Zeiten finanziell unterst\u00fctzen wollen, dann freuen wir uns \u00fcber<a href=\"https:\/\/www.frei-zeit-haus.de\/spenden\/spenden.html\">\u00a0kleine und gro\u00dfe Spenden.<\/a>\u00a0Sprechen Sie uns gerne dazu an!<br>Spendenquittungen k\u00f6nnen wir selbstverst\u00e4ndlich ausstellen:<\/em><\/p>\n\n\n\n<p>GLS Bank<br>IBAN DE 85 4306 0967 1145 4622 00<br>BIC:GENODEM1GLS<\/p>\n\n\n\n<p>Ganz unabh\u00e4ngig davon, w\u00fcnschen wir Ihnen von Herzen einen gesunden Jahresausklang und ein freundliches und gutes neues Jahr mit vielen spannenden Begegnungen.<\/p>\n\n\n\n<p>Nat\u00fcrlich freuen wir uns, wenn wir Sie in 2026 in einer unserer <a href=\"https:\/\/www.frei-zeit-haus.de\/projekte.html\">Einrichtungen<\/a>&nbsp;und zu unseren Angeboten begr\u00fc\u00dfen d\u00fcrfen.<\/p>\n\n\n\n<p>Sie sind jederzeit herzlich willkommen, sich bei uns zu treffen, zu diskutieren, sich zu engagieren, zu tanzen, zu feiern oder mit und voneinander zu lernen.<br><br>Mit den besten W\u00fcnschen f\u00fcr das neue Jahr,<\/p>\n\n\n\n<p>Anne Lemberg<br>Gesch\u00e4ftsf\u00fchrerin des FreiZeitHaus e.V.<br>Und der Vorstand des FreiZeitHaus e.V.<br>Stefanie Str\u00fcmpfer, Stefan Senkel, Doreen Buske, Christoph Lewek und Jacob Hauptmann<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"765\" src=\"https:\/\/www.unser-weissensee.de\/wp-content\/uploads\/2025\/12\/weihnachten2025.png\" alt=\"Weihnachtsgru\u00df\" class=\"wp-image-3312\" style=\"aspect-ratio:1.3071895921472274;width:470px;height:auto\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Mitglieder des FreiZeitHaus e.V., liebe ehrenamtlich Engagierte in unseren Einrichtungen, am Jahresende erz\u00e4hlen viele von runden Erfolgen. Von Kurven, die nach oben zeigen, und erfolgreich \u201eeinget\u00fcteten\u201c Projekten. Die Geschichten, die uns in unserer Arbeit begegnen sehen an manchen Stellen [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,7,9,38],"tags":[],"class_list":["post-3310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-60-in-weissensee","category-aktivitaeten-fuer-familien","category-ehrenamt-in-weissensee","category-initiativen-berichten"],"_links":{"self":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/3310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/comments?post=3310"}],"version-history":[{"count":3,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/3310\/revisions"}],"predecessor-version":[{"id":3314,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/3310\/revisions\/3314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/media\/3312"}],"wp:attachment":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/media?parent=3310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/categories?post=3310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/tags?post=3310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}