{"id":3008,"date":"2025-05-21T09:31:19","date_gmt":"2025-05-21T09:31:19","guid":{"rendered":"https:\/\/www.unser-weissensee.de\/?p=3008"},"modified":"2025-05-21T09:31:20","modified_gmt":"2025-05-21T09:31:20","slug":"ich-will-sicher-zur-schule-demoaufruf","status":"publish","type":"post","link":"https:\/\/www.unser-weissensee.de\/index.php\/2025\/05\/21\/ich-will-sicher-zur-schule-demoaufruf\/","title":{"rendered":"Ich will sicher zur Schule &#8211; Demoaufruf"},"content":{"rendered":"\n<p>Liebe Freund*innen in und um Wei\u00dfensee,<\/p>\n\n\n\n<p>wir wollen euch gern zu unserer kidical mass n\u00e4chsten Samstag ab Antonplatz einladen! Wir freuen uns wenn ihr den Aufruf flei\u00dfig \u00fcber eure Netzwerke teilt.<\/p>\n\n\n\n<p>Seit inzwischen mehr als zehn Jahren wird in Wei\u00dfensee auf der Berliner Allee die Verkehrswende blockiert: es gibt immer noch keine Fahrradwege und kaum sichere Querungsm\u00f6glichkeiten, daf\u00fcr zu viel und zu lauten Autoverkehr. Das ist eine Gefahr f\u00fcr alle die um die Allee herum wohnen und leben, insbesondere f\u00fcr Kinder und andere besonders gef\u00e4hrdete Gruppen.<\/p>\n\n\n\n<p>Nun soll die Allee weiter saniert werden, wenn es nach dem Senat ginge &#8222;autogerecht&#8220;. Aber nicht mit uns, wir fordern eine Berliner Allee f\u00fcr Alle anstatt nur f\u00fcr Autos!<\/p>\n\n\n\n<p><strong>Deshalb ruft die Aktion Berliner Allee am 24.05. um 11 Uhr zu einer Fahrraddemo mit Kindern auf der Allee auf, um zu zeigen, dass wir nicht die Kosten f\u00fcr eine r\u00fcckw\u00e4rtsgewandte, Verkehrspolitik tragen werden.<\/strong><\/p>\n\n\n\n<p>Radwege an die Allee und alle anderen Hauptverkehrsstra\u00dfen!<\/p>\n\n\n\n<p>Verkehrspolitik f\u00fcr Menschen, nicht f\u00fcr Autos!<\/p>\n\n\n\n<p><strong>Treffpunkt:<\/strong> Antonplatz<\/p>\n\n\n\n<p><strong>Zeit:<\/strong> 24.05. 11 Uhr<\/p>\n\n\n\n<p>Weitere Informationen: <a href=\"https:\/\/aktionberlinerallee.de\/\">aktionberlinerallee.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Freund*innen in und um Wei\u00dfensee, wir wollen euch gern zu unserer kidical mass n\u00e4chsten Samstag ab Antonplatz einladen! Wir freuen uns wenn ihr den Aufruf flei\u00dfig \u00fcber eure Netzwerke teilt. Seit inzwischen mehr als zehn Jahren wird in Wei\u00dfensee [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[270,43,271,61,60,131,41],"class_list":["post-3008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initiativen-berichten","tag-aktionberlinerallee","tag-berlin","tag-fahrraddemo","tag-familien","tag-kinder","tag-nachbarschaft","tag-weissensee"],"_links":{"self":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/3008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/comments?post=3008"}],"version-history":[{"count":2,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/3008\/revisions"}],"predecessor-version":[{"id":3011,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/3008\/revisions\/3011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/media\/3009"}],"wp:attachment":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/media?parent=3008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/categories?post=3008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/tags?post=3008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}