{"id":2792,"date":"2025-02-12T07:57:34","date_gmt":"2025-02-12T07:57:34","guid":{"rendered":"https:\/\/www.unser-weissensee.de\/?p=2792"},"modified":"2025-02-12T08:01:33","modified_gmt":"2025-02-12T08:01:33","slug":"demokratiewochen-im-stadtteilzentrum-weissensee-vom-10-02-bis-zum-23-02","status":"publish","type":"post","link":"https:\/\/www.unser-weissensee.de\/index.php\/2025\/02\/12\/demokratiewochen-im-stadtteilzentrum-weissensee-vom-10-02-bis-zum-23-02\/","title":{"rendered":"Demokratiewochen im Stadtteilzentrum Wei\u00dfensee vom 10.02. bis zum 23.02."},"content":{"rendered":"\n<p>W\u00e4hlen ist ein Grundrecht f\u00fcr B\u00fcrger und B\u00fcrgerinnen. Das Recht zu w\u00e4hlen geh\u00f6rt zu den wichtigsten Rechten, die B\u00fcrger und B\u00fcrgerinnen in Deutschland haben. Durch Wahlen k\u00f6nnen Sie in der Politik mitbestimmen.<\/p>\n\n\n\n<p>Wir veranstalten am <strong>18.02. von 19:00 bis 20:30<\/strong> einen <strong>Kandidat*innencheck <\/strong>im Stadtteilzentrum. Dazu haben wir Alexandra Wend (SPD), Franziska Dezember (CDU), Julia Schneider (B\u00fcndnis 90\/Die Gr\u00fcnen), Maximilian Schirmer (Die Linke) und Sven Hoffmeister (FDP) eingeladen. Nutze die Gelegenheit, deine Fragen direkt zu stellen und die Direktkandidat*innen pers\u00f6nlich kennenzulernen. Mathias Furch wird die Podiumsdiskussion moderieren.<\/p>\n\n\n\n<p>Am <strong>13.02. von 12.30 bis 17:30<\/strong> kommt die \u201eGesellschaft im Wandel gGmbH\u201c mit ihrem Tiny House zu uns in den Garten.&nbsp; In dem rollenden \u201eRaum f\u00fcr Demokratie\u201c wollen wir mit euch ins Gespr\u00e4ch kommen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mieten und Wohnen: Wie bleiben unsere Bezirke bezahlbar und lebenswert?<\/li>\n\n\n\n<li>\u00c4lter werden in der Stadt: Was brauchen wir f\u00fcr eine gute Versorgung und mehr Lebensqualit\u00e4t?<\/li>\n\n\n\n<li>Gemeinschaft und Teilhabe: Wie schaffen wir ein Miteinander, das niemanden ausschlie\u00dft?<\/li>\n<\/ul>\n\n\n\n<p>Lasst uns die Themen angehen, die unser Zusammenleben im Bezirk betreffen. Bringt eure Ideen ein, h\u00f6rt zu oder kommt einfach ins Gespr\u00e4ch.<\/p>\n\n\n\n<p>Wer noch nicht sicher ist, wo das Kreuz gesetzt wird, kann am <strong>14.02.<\/strong> und <strong>18.02.<\/strong> zwischen <strong>11:00 und 17:00 Uhr<\/strong> den <strong>Wahl-O-Mat<\/strong> bei uns im Haus nutzen. Alle 29 Parteien, die zur Wahl antreten, haben die Wahl-O-Mat-Thesen beantwortet. Vergleiche deine Standpunkte mit den Antworten der Parteien. Wir stellen einen Computer mit Internetzugang bereit und unterst\u00fctzen bei der Bedienung. Der Wahl-O-Mat kann auch von zu Hause oder vom Handy genutzt werde. Hier gelangt ihr zu der Website: <a href=\"http:\/\/www.wahl-o-mat.de\" rel=\"noreferrer noopener\" target=\"_blank\">www.wahl-o-mat.de<\/a><\/p>\n\n\n\n<p>Alle Parteien, die in der letzten Legislaturperiode im Bundestag sa\u00dfen, haben zuvor viele Versprechen gemacht. Auf dieser Basis haben wir sie gew\u00e4hlt. Aber: Was bleibt davon \u00fcbrig und wie haben sie wirklich gehandelt? Der <strong>Real-O-Mat<\/strong> schaut nicht auf die Wahlversprechen, sondern gleicht das tats\u00e4chliche Abstimmungsverhalten der Parteien zu aktuellen politischen Themen mit Ihrer pers\u00f6nlichen Position ab. Grundlage sind dabei Antr\u00e4ge und Gesetzentw\u00fcrfe im Bundestag. Die Nutzung ist ebenfalls am 14.02. und 18.02. bei uns im Stadtteilzentrum m\u00f6glich, oder ganz bequem von zu Hause \u00fcber diese Website: <a href=\"http:\/\/www.real-o-mat.de\" rel=\"noreferrer noopener\" target=\"_blank\">www.real-o-mat.de<\/a><\/p>\n\n\n\n<p>Informiert euch \u00fcber die Vorhaben und Versprechen der Parteien. Wir haben die <strong>Wahlprogramme<\/strong> der einzelnen Parteien als Leseexemplar im Gartensaal ausgelegt.<\/p>\n\n\n\n<p>Mehr als 59 Millionen Menschen d\u00fcrfen den Bundestag am 23.02.25 w\u00e4hlen. 2,3 Millionen sogar das erste Mal!Was macht der Bundestag? Wie w\u00e4hlt man? Was sind Erst- und Zweitstimme? Was geschieht nach der Wahl? Informationen rund um das Thema Bundestagswahl findest du bei der Bundezentrale f\u00fcr politische Bildung, die du \u00fcber die Website <a href=\"http:\/\/www.bpb.de\" rel=\"noreferrer noopener\" target=\"_blank\">www.bpb.de<\/a> erreicht. Auch bei uns im Gartensaal findest du Magazine und Informationsbrosch\u00fcren als Leseexemplare.<\/p>\n\n\n\n<p>Warum w\u00e4hlst du? Welch Themen sind dir wichtig? Besuche uns auf eine Tasse Kaffee und tausche dich mit deinen Nachbar*innen aus, <strong>denn am 23. Februar 2025 ist Bundestagswahl.&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hlen ist ein Grundrecht f\u00fcr B\u00fcrger und B\u00fcrgerinnen. Das Recht zu w\u00e4hlen geh\u00f6rt zu den wichtigsten Rechten, die B\u00fcrger und B\u00fcrgerinnen in Deutschland haben. Durch Wahlen k\u00f6nnen Sie in der Politik mitbestimmen. Wir veranstalten am 18.02. von 19:00 bis 20:30 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2795,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[43,255,256,58,131,69,257,41],"class_list":["post-2792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initiativen-berichten","tag-berlin","tag-demokratie","tag-demokratiewochen","tag-freizeithause-v","tag-nachbarschaft","tag-stz-weissensee","tag-wahlen2025","tag-weissensee"],"_links":{"self":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/2792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/comments?post=2792"}],"version-history":[{"count":1,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/2792\/revisions"}],"predecessor-version":[{"id":2794,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/posts\/2792\/revisions\/2794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/media\/2795"}],"wp:attachment":[{"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/media?parent=2792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/categories?post=2792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unser-weissensee.de\/index.php\/wp-json\/wp\/v2\/tags?post=2792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}